{"id":24641,"date":"2023-11-02T11:30:50","date_gmt":"2023-11-02T16:30:50","guid":{"rendered":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/preventa-buen-fin-hoteles-en-tulum-2"},"modified":"2023-11-21T08:06:25","modified_gmt":"2023-11-21T13:06:25","slug":"buen-fin-hoteles-en-tulum","status":"publish","type":"dynamic-landing","link":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum","title":{"rendered":"\u00a1Buen Fin! Hoteles en Tulum"},"featured_media":20778,"parent":0,"template":"","class_list":["post-24641","dynamic-landing","type-dynamic-landing","status-publish","has-post-thumbnail","hentry"],"acf":{"landing_tipo":"hotel","configuraciones_hotel":{"cargar_hoteles_dede_archivo_":0,"importar_hoteles_de_csv":null,"hoteles":["{\"id\":35717,\"code\":\"111726\",\"name\":\"Grand Oasis Tulum Riviera\"}","{\"id\":676922,\"code\":\"488013\",\"name\":\"The Sens Tulum Riviera\"}","{\"id\":642071,\"code\":\"472921\",\"name\":\"Secrets Tulum Resort & Beach Club\"}","{\"id\":19287,\"code\":\"100177\",\"name\":\"Dreams Tulum Resort & Spa\"}","{\"id\":614307,\"code\":\"444578\",\"name\":\"Hotel Bardo\"}","{\"id\":481001,\"code\":\"314795\",\"name\":\"Una Vida\"}","{\"id\":24109,\"code\":\"100022\",\"name\":\"Bahia Principe Grand Tulum\"}","{\"id\":617082,\"code\":\"447432\",\"name\":\"Hilton Tulum Riviera Maya, An All Inclusive Resort\"}","{\"id\":643960,\"code\":\"475029\",\"name\":\"La Diosa Tulum\"}","{\"id\":610782,\"code\":\"440990\",\"name\":\"Zereno Luxury Boutique Hotel\"}","{\"id\":19268,\"code\":\"100157\",\"name\":\"Catalonia Royal Tulum - Solo Adultos\"}","{\"id\":587491,\"code\":\"417205\",\"name\":\"Hotel CARPE DIEM Tulum by Nah Hotels\"}","{\"id\":602347,\"code\":\"432486\",\"name\":\"Villa Las Estrellas Tulum - Located at the Party Zone\"}","{\"id\":413614,\"code\":\"241574\",\"name\":\"Unico Hotel Riviera Maya Adults Only\"}","{\"id\":410003,\"code\":\"238039\",\"name\":\"Tago Tulum by G Hotels\"}","{\"id\":24279,\"code\":\"101910\",\"name\":\"Be Tulum Beach & Spa Resort\"}","{\"id\":640777,\"code\":\"471818\",\"name\":\"Motto by Hilton Tulum\"}"],"ordenamiento":"0","tipo_fecha_cotizacion":"1","fecha_estatica_inicio":null,"fecha_estatica_fin":null,"tipo_1_dias":20,"tipo_1_estancia":3},"vigencia_desde":"","vigencia_hasta":"2023-11-29 00:00:00","colores":{"banner":"rgb(221,0,0)","pleca_hotel":"","textos":"#000","bg_precio":"","bg_destino":"rgba(0,0,0,0.37)"},"banner_setings":{"font_color":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Buen Fin! Hoteles en Tulum - PriceTravel<\/title>\n<meta name=\"description\" content=\"\u00bfQuieres disfrutar de unas vacaciones en Tulum al mejor precio? Aprovecha las ofertas del Buen Fin. \u00a1No esperes m\u00e1s!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Buen Fin! Hoteles en Tulum - PriceTravel\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres disfrutar de unas vacaciones en Tulum al mejor precio? Aprovecha las ofertas del Buen Fin. \u00a1No esperes m\u00e1s!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum\" \/>\n<meta property=\"og:site_name\" content=\"PriceTravel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PriceTravel\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-21T13:06:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2023\/09\/fondo_Tulum_1050x350_72HRSOF.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PriceTravel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum\",\"url\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum\",\"name\":\"\u00a1Buen Fin! Hoteles en Tulum - PriceTravel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/fondo_Tulum_1050x350_72HRSOF.jpg\",\"datePublished\":\"2023-11-02T16:30:50+00:00\",\"dateModified\":\"2023-11-21T13:06:25+00:00\",\"description\":\"\u00bfQuieres disfrutar de unas vacaciones en Tulum al mejor precio? Aprovecha las ofertas del Buen Fin. \u00a1No esperes m\u00e1s!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum#primaryimage\",\"url\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/fondo_Tulum_1050x350_72HRSOF.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/fondo_Tulum_1050x350_72HRSOF.jpg\",\"width\":1050,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/buen-fin-hoteles-en-tulum#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Buen Fin! Hoteles en Tulum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/#website\",\"url\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/\",\"name\":\"PriceTravel\",\"description\":\"M\u00e9xico, por ti viajar\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/#organization\",\"name\":\"PriceTravel.com\",\"url\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pricetravel.png\",\"contentUrl\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pricetravel.png\",\"width\":422,\"height\":56,\"caption\":\"PriceTravel.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pricetravel.com\\\/es\\\/ofertas-de-viajes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PriceTravel\",\"https:\\\/\\\/x.com\\\/PriceTravel\",\"https:\\\/\\\/www.instagram.com\\\/pricetravel\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Buen Fin! Hoteles en Tulum - PriceTravel","description":"\u00bfQuieres disfrutar de unas vacaciones en Tulum al mejor precio? Aprovecha las ofertas del Buen Fin. \u00a1No esperes m\u00e1s!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Buen Fin! Hoteles en Tulum - PriceTravel","og_description":"\u00bfQuieres disfrutar de unas vacaciones en Tulum al mejor precio? Aprovecha las ofertas del Buen Fin. \u00a1No esperes m\u00e1s!","og_url":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum","og_site_name":"PriceTravel","article_publisher":"https:\/\/www.facebook.com\/PriceTravel","article_modified_time":"2023-11-21T13:06:25+00:00","og_image":[{"width":1050,"height":350,"url":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2023\/09\/fondo_Tulum_1050x350_72HRSOF.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PriceTravel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum","url":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum","name":"\u00a1Buen Fin! Hoteles en Tulum - PriceTravel","isPartOf":{"@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum#primaryimage"},"image":{"@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum#primaryimage"},"thumbnailUrl":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2023\/09\/fondo_Tulum_1050x350_72HRSOF.jpg","datePublished":"2023-11-02T16:30:50+00:00","dateModified":"2023-11-21T13:06:25+00:00","description":"\u00bfQuieres disfrutar de unas vacaciones en Tulum al mejor precio? Aprovecha las ofertas del Buen Fin. \u00a1No esperes m\u00e1s!","breadcrumb":{"@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum#primaryimage","url":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2023\/09\/fondo_Tulum_1050x350_72HRSOF.jpg","contentUrl":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2023\/09\/fondo_Tulum_1050x350_72HRSOF.jpg","width":1050,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/buen-fin-hoteles-en-tulum#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes"},{"@type":"ListItem","position":2,"name":"\u00a1Buen Fin! Hoteles en Tulum"}]},{"@type":"WebSite","@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/#website","url":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/","name":"PriceTravel","description":"M\u00e9xico, por ti viajar\u00e9","publisher":{"@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/#organization","name":"PriceTravel.com","url":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/#\/schema\/logo\/image\/","url":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2022\/08\/pricetravel.png","contentUrl":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2022\/08\/pricetravel.png","width":422,"height":56,"caption":"PriceTravel.com"},"image":{"@id":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PriceTravel","https:\/\/x.com\/PriceTravel","https:\/\/www.instagram.com\/pricetravel\/"]}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/dynamic-landing\/24641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/dynamic-landing"}],"about":[{"href":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/types\/dynamic-landing"}],"version-history":[{"count":0,"href":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/dynamic-landing\/24641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/media\/20778"}],"wp:attachment":[{"href":"https:\/\/www.pricetravel.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/media?parent=24641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}